{"id":527575,"date":"2019-08-28T10:09:50","date_gmt":"2019-08-28T10:09:50","guid":{"rendered":"http:\/\/www.webuildvalue.com\/?p=527575"},"modified":"2020-10-18T18:29:34","modified_gmt":"2020-10-18T18:29:34","slug":"le-metro-driverless-alla-conquista-del-mondo-2","status":"publish","type":"post","link":"https:\/\/www.webuildvalue.com\/it\/megatrend\/le-metro-driverless-alla-conquista-del-mondo-2.html","title":{"rendered":"Le metro driverless alla conquista del mondo"},"content":{"rendered":"\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"869\" src=\"http:\/\/www.webuildvalue.com\/wp-content\/uploads\/The-growing-popularity-of-driverless-metros-1024x463.jpg\" alt=\"Le metro driverless alla conquista del mondo | Dubai Metro Network\" class=\"wp-image-527560\" srcset=\"https:\/\/www.webuildvalue.com\/wp-content\/uploads\/The-growing-popularity-of-driverless-metros-1024x463.jpg 1024w, https:\/\/www.webuildvalue.com\/wp-content\/uploads\/The-growing-popularity-of-driverless-metros-300x136.jpg 300w, https:\/\/www.webuildvalue.com\/wp-content\/uploads\/The-growing-popularity-of-driverless-metros-768x348.jpg 768w, https:\/\/www.webuildvalue.com\/wp-content\/uploads\/The-growing-popularity-of-driverless-metros.jpg 1920w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/><\/figure>\n\n\n\n<p>Oltre mille chilometri di <strong>linee metropolitane driverless<\/strong> attive in tutto il mondo. \u00c8 questo l\u2019ultimo dato che conferma la diffusione di questo nuovo sistema di trasporto su ferro, in special modo in Asia dove moltissime citt\u00e0 stanno investendo sul trasporto pubblico per rispondere ai bisogni di una popolazione che cresce di giorno in giorno.<br>Dall\u2019inaugurazione della prima <strong>metro driverless<\/strong>, avvenuta nel <strong>1981 a Kobe, in Giappone<\/strong>, lo sviluppo di questo genere di tecnologia \u00e8 stato costante ma a ritmi contenuti.<br>Ci sono infatti voluti 30 anni prima che la distanza totale coperta da queste linee raggiungesse i 500 chilometri, una lunghezza uguale al combinato delle metro di Lille, Vancouver e San Paolo. Ma da quel momento<strong> il tasso di crescita della nuova tecnologia \u00e8 aumentato in modo significativo.<\/strong><br>Secondo quanto riporta l\u2019Osservatorio sulle <strong>metro automatiche<\/strong> (pubblicato dall\u2019International Association of Public Transport, UITP), negli ultimi otto anni la lunghezza delle <strong>linee driverless<\/strong> \u00e8 infatti raddoppiata raggiungendo i 1.000 chilometri, celebrati con l\u2019apertura della Pujiang Line di Shanghai.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Una crescita esponenziale<\/h2>\n\n\n\n<p>Ram\u00f3n Malla, presidente dell\u2019Osservatorio, \u00e8 convinto che la crescita continuer\u00e0 su ritmi sostenuti anche per i prossimi anni. <strong>\u00abL\u2019evoluzione delle metro driverless proseguir\u00e0 ancora pi\u00f9 rapida nel prossimo decennio\u00bb<\/strong> ha dichiarato in un comunicato stampa ufficiale dell\u2019Associazione.<br>Entro il 2028, potranno infatti essere operativi 3.800 chilometri di linee driverless, un numero quasi quattro volte superiore rispetto ai 1.000 chilometri registrati nel marzo del 2018.<br>\u00abLa maggior parte di questa crescita \u2013 si legge ancora nel comunicato \u2013 dipende dalle 87 linee oggi in costruzione, per cui si attende una futura apertura\u00bb.<br><strong>La maggior parte di queste metro sono realizzate in Asia, e ben 37 sul totale in Cina.<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"1257\" height=\"1257\" src=\"http:\/\/www.webuildvalue.com\/wp-content\/uploads\/20190731-Driverless_ITA-1024x1024.jpg\" alt=\"20190731 Driverless_ITA\" class=\"wp-image-527562\" srcset=\"https:\/\/www.webuildvalue.com\/wp-content\/uploads\/20190731-Driverless_ITA-1024x1024.jpg 1024w, https:\/\/www.webuildvalue.com\/wp-content\/uploads\/20190731-Driverless_ITA-150x150.jpg 150w, https:\/\/www.webuildvalue.com\/wp-content\/uploads\/20190731-Driverless_ITA-300x300.jpg 300w, https:\/\/www.webuildvalue.com\/wp-content\/uploads\/20190731-Driverless_ITA-768x768.jpg 768w, https:\/\/www.webuildvalue.com\/wp-content\/uploads\/20190731-Driverless_ITA.jpg 1257w\" sizes=\"auto, (max-width: 1257px) 100vw, 1257px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">La soluzione migliore per il trasporto cittadino<\/h2>\n\n\n\n<p>Lo sviluppo delle nuove metro conferma che <strong>il beneficio in termini di mobilit\u00e0 \u00e8 elevato<\/strong>. Questa \u00e8 anche l\u2019opinione di Laurent Dauby, Direttore Rail Transport della UITP. <strong>Le metro completamente automatizzate \u2013 dove i treni operano senza conducente \u2013 sono flessibili, capaci di variare l\u2019intensit\u00e0 e il ritmo del servizio durante il giorno, e anche pi\u00f9 sicure perch\u00e9 viene ridotta a zero la possibilit\u00e0 di un errore umano. <\/strong>Oltre a questo, garantiscono un risparmio energetico proprio perch\u00e9, grazie alla completa automazione, sono in grado di operare in modo pi\u00f9 efficiente.<br>Tutti benefici che si aggiungono a quelli delle linee metropolitane tradizionali, e <strong>quindi la riduzione del traffico e dell\u2019inquinamento<\/strong>.<br><strong>Secondo i calcoli dell\u2019Associazione le linee driverless nel mondo oggi operative sono 63, attive in 42 citt\u00e0 e 19 paesi. <\/strong>In altre parole, quasi un quarto delle reti metropolitane presenti nel mondo \u00e8 dotato di almeno una linea completamente automatizzata.<br>La loro adozione non conosce confini e spazia dall\u2019Europa all\u2019Australia. Proprio in Australia Sydney ha inaugurato da poco la <strong>Sydney Metro North West<\/strong>, la prima nel suo genere del paese, dove il ponte e il viadotto della metro sono stati realizzati da Salini Impregilo. A Copenhagen, nel prossimo autunno, sar\u00e0 inaugurata invece la metro Cityringen, altro esempio di linea driverless interamente costruita da <strong>Salini Impregilo<\/strong>, mentre a Milano il gruppo sta costruendo la M4, la linea che collegher\u00e0 l\u2019aeroporto di Linate con il centro della citt\u00e0.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Il boom asiatico<\/h2>\n\n\n\n<p>Rispetto al totale dei 1.026 chilometri di <strong>linee driverless<\/strong> attivi alla fine del 2018, la met\u00e0 sono in Asia. Un dato che rende la regione <strong>prima al mondo nello sviluppo e nell\u2019adozione di questa tecnologia<\/strong>.<br>Questo risultato \u00e8 possibile grazie all\u2019apertura di cinque linee automatizzate in Corea del Sud, Malesia e Cina solo negli ultimi due anni.<br>In questa particolare classifica <strong>l\u2019Europa occupa invece il secondo posto, con il 30% delle linee driverless al mondo, seguita da Nord America e Medio Oriente<\/strong> rispettivamente con l\u201911 e l\u20198%. Segue in coda il Sud America dove solo l\u20191% delle metropolitane sono senza conducente.<br>Nel complesso le <strong>metro driverless<\/strong> rappresentano solo il 7% del totale mondiale, ma la loro \u00e8 una storia recente. E tutti gli esperti del settore assicurano che il <strong>futuro della mobilit\u00e0 sostenibile sar\u00e0 affidato interamente a loro<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Oltre mille chilometri di linee metropolitane driverless attive in tutto il mondo. \u00c8 questo l\u2019ultimo dato che conferma la diffusione di questo nuovo sistema di trasporto su ferro, in special modo in Asia dove moltissime citt\u00e0 stanno investendo sul trasporto pubblico per rispondere ai bisogni di una popolazione che cresce di giorno in giorno.Dall\u2019inaugurazione della [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":527571,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[6],"tags":[18980,18983,18989,18994,18996],"yst_prominent_words":[14717,2668,8220,17385,8223,14871,14753,15283,1036,8221,1402,8222,16283],"class_list":["post-527575","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-megatrend","tag-europa","tag-green-mobility","tag-nuove-tecnologie","tag-sviluppo-e-crescita","tag-trasporti"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.webuildvalue.com\/it\/wp-json\/wp\/v2\/posts\/527575","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.webuildvalue.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.webuildvalue.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.webuildvalue.com\/it\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.webuildvalue.com\/it\/wp-json\/wp\/v2\/comments?post=527575"}],"version-history":[{"count":6,"href":"https:\/\/www.webuildvalue.com\/it\/wp-json\/wp\/v2\/posts\/527575\/revisions"}],"predecessor-version":[{"id":541291,"href":"https:\/\/www.webuildvalue.com\/it\/wp-json\/wp\/v2\/posts\/527575\/revisions\/541291"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.webuildvalue.com\/it\/wp-json\/wp\/v2\/media\/527571"}],"wp:attachment":[{"href":"https:\/\/www.webuildvalue.com\/it\/wp-json\/wp\/v2\/media?parent=527575"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.webuildvalue.com\/it\/wp-json\/wp\/v2\/categories?post=527575"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.webuildvalue.com\/it\/wp-json\/wp\/v2\/tags?post=527575"},{"taxonomy":"yst_prominent_words","embeddable":true,"href":"https:\/\/www.webuildvalue.com\/it\/wp-json\/wp\/v2\/yst_prominent_words?post=527575"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}